{"id":8165,"date":"2024-09-14T10:19:07","date_gmt":"2024-09-14T10:19:07","guid":{"rendered":"https:\/\/ateliersposiformichella.com\/?post_type=product&#038;p=8165"},"modified":"2025-10-07T08:17:20","modified_gmt":"2025-10-07T08:17:20","slug":"khloe","status":"publish","type":"product","link":"https:\/\/www.ateliersposiformichella.com\/index.php\/product\/khloe\/","title":{"rendered":"KHLOE"},"content":{"rendered":"<table id=\"product-attribute-specs-table\" class=\"data table additional-attributes\">\n<tbody>\n<tr>\n<th class=\"col label\" scope=\"row\">Taglio<\/th>\n<td class=\"col data\" data-th=\"Taglio\">Principessa<\/td>\n<\/tr>\n<tr>\n<th class=\"col label\" scope=\"row\">Scollatura<\/th>\n<td class=\"col data\" data-th=\"Scollatura\">Senza spalline<\/td>\n<\/tr>\n<tr>\n<th class=\"col label\" scope=\"row\">Tessuti<\/th>\n<td class=\"col data\" data-th=\"Tessuti\">Mikado<\/td>\n<\/tr>\n<tr>\n<th class=\"col label\" scope=\"row\">Scollatura Schiena<\/th>\n<td class=\"col data\" data-th=\"Scollatura Schiena\">Altri<\/td>\n<\/tr>\n<tr>\n<th class=\"col label\" scope=\"row\">Maniche<\/th>\n<td class=\"col data\" data-th=\"Maniche\">Senza maniche<\/td>\n<\/tr>\n<tr>\n<th class=\"col label\" scope=\"row\">Girovita<\/th>\n<td class=\"col data\" data-th=\"Girovita\">Vita<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul class=\"faqs\">\n<li><strong>POSSO PERSONALIZZARE QUESTO ABITO?<\/strong><\/li>\n<\/ul>\n<p>S\u00ec, a seconda del modello, si possono apportare modifiche alla lunghezza dello strascico, alla lunghezza delle maniche e alla forma e\/o profondit\u00e0 della scollatura.<\/p>\n<ul class=\"faqs\">\n<li><strong>CON QUANTO ANTICIPO DEVO ORDINARE IL MIO ABITO?<\/strong><\/li>\n<\/ul>\n<p>Si consiglia di ordinare l\u2019abito 9-12 mesi prima della data del matrimonio. Abbiamo anche abiti pronti da provare e portare a casa il giorno stesso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Scopri il fascino delicato di questo abito a principessa, realizzato in mikado. La morbidezza del tessuto esalta il drappeggio del corpetto, che presenta una scollatura senza spalline. La gonna \u00e8 arricchita da tasche e da una coda a cattedrale.<\/strong><\/p>\n","protected":false},"featured_media":9859,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[32,42,45],"product_tag":[],"class_list":{"0":"post-8165","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pronovias","7":"product_cat-pronovias-sposa","8":"product_cat-sposa","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/product\/8165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/comments?post=8165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/media\/9859"}],"wp:attachment":[{"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/media?parent=8165"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=8165"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=8165"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ateliersposiformichella.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=8165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}